{"id":982,"date":"2024-03-21T15:23:19","date_gmt":"2024-03-21T14:23:19","guid":{"rendered":"https:\/\/www.bds-bayern.de\/olching\/danke-an-karin-horn-fuer-ihren-einsatz-im-bds-bayern\/"},"modified":"2024-03-21T15:23:19","modified_gmt":"2024-03-21T14:23:19","slug":"danke-an-karin-horn-fuer-ihren-einsatz-im-bds-bayern","status":"publish","type":"post","link":"https:\/\/www.bds-bayern.de\/olching\/danke-an-karin-horn-fuer-ihren-einsatz-im-bds-bayern\/","title":{"rendered":"Danke an Karin Horn f\u00fcr ihren Einsatz im BDS Bayern"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.shortcode-single-image-wrap.shortcode-single-image-9adcdebd2cf16a127f25f1a9fa058be5.enable-bg-rollover .rollover i,\n.shortcode-single-image-wrap.shortcode-single-image-9adcdebd2cf16a127f25f1a9fa058be5.enable-bg-rollover .rollover-video i {\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.shortcode-single-image-wrap.shortcode-single-image-9adcdebd2cf16a127f25f1a9fa058be5 .rollover-icon {\n  font-size: 32px;\n  color: #ffffff;\n  min-width: 44px;\n  min-height: 44px;\n  line-height: 44px;\n  border-radius: 100px;\n  border-style: solid;\n  border-width: 0px;\n}\n.dt-icon-bg-on.shortcode-single-image-wrap.shortcode-single-image-9adcdebd2cf16a127f25f1a9fa058be5 .rollover-icon {\n  background: rgba(255,255,255,0.3);\n  box-shadow: none;\n}<\/style>[vc_column_text]<strong><span style=\"font-family: 'Times',serif\">Liebe Vorst\u00e4nde, Mitglieder und Freunde des BDS,<\/span><\/strong><\/p>\n<p><span style=\"font-family: 'Times',serif\">mit einem weinenden und einem lachenden Auge m\u00f6chte ich mich heute von Ihnen \/ Euch verabschieden. Nach \u00fcber 5 Jahren als Bezirksgesch\u00e4ftsf\u00fchrerin Niederbayern und Initiatorin der BDS Social Media Akademie habe ich mich dazu entschlossen, wieder in die freie Wirtschaft zur\u00fcckzukehren.<\/span><\/p>\n<p><span style=\"font-family: 'Times',serif\">Die Jahre im BDS und im Bezirk Niederbayern waren f\u00fcr mich wundervoll und ich bin dankbar f\u00fcr all die Begegnungen und Erfahrungen, die mir w\u00e4hrend meiner Zeit beim BDS geschenkt wurden. Ich durfte viele gro\u00dfartige Menschen kennenlernen, die nicht nur meine Kollegen, sondern auch meine Freunde wurden. Es war mir stets eine Herzensangelegenheit, den Mittelstand zu unterst\u00fctzen und die BDS Ziele voranzutreiben.<\/span><\/p>\n<p><span style=\"font-family: 'Times',serif\">Ich m\u00f6chte Ihnen \/ Euch allen von Herzen f\u00fcr die Zusammenarbeit und die wertvolle Zeit danken. Es war mir eine Ehre, Teil des BDS-Netzwerks zu sein und gemeinsam mit Ihnen \/ Euch den Mittelstand voranzubringen.<\/span><\/p>\n<p><span style=\"font-family: 'Times',serif\">Ich freue mich auf das, was die Zukunft f\u00fcr mich bereith\u00e4lt und bin zuversichtlich, dass wir uns auf unseren Wegen wieder begegnen werden.<\/span><\/p>\n<p><span style=\"font-family: 'Times',serif\">Bis dahin w\u00fcnsche ich Ihnen \/ Euch allen weiterhin viel Erfolg, Freude und Erf\u00fcllung bei der Arbeit und nat\u00fcrlich auch privat.\u00a0<\/span><\/p>\n<p><span style=\"font-family: 'Times',serif\">Bleiben Sie dem BDS verbunden und setzen Sie sich weiterhin engagiert f\u00fcr den Mittelstand ein.<\/span><\/p>\n<p><span style=\"font-family: 'Times',serif\">Servus, pfiats eich und auf bald<\/span><\/p>\n<p><span style=\"font-family: 'Times',serif\">Karin Horn (Pecher)<\/span><\/p>\n<p>Der BDS Bayern bedankt sich aufrichtig bei Karin Horn f\u00fcr die geleistete Arbeit und w\u00fcnscht ihr f\u00fcr die Zukunft alles Gute![\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Liebe Vorst\u00e4nde, Mitglieder und Freunde des BDS,<br \/>\nmit einem weinenden und einem lachenden Auge m\u00f6chte ich mich heute von Ihnen \/ Euch verabschieden. Nach \u00fcber 5 Jahren als Bezirksgesch\u00e4ftsf\u00fchrerin Niederbayern und Initiatorin der BDS Social Media Akademie habe ich mich dazu entschlossen, wieder in die freie Wirtschaft zur\u00fcckzukehren.<\/p>\n","protected":false},"author":1,"featured_media":983,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,8,7],"tags":[],"class_list":["post-982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bds-intern","category-hauptgeschaeftsstelle","category-presse-veroeffentlichungen","category-20","category-8","category-7","description-off"],"_links":{"self":[{"href":"https:\/\/www.bds-bayern.de\/olching\/wp-json\/wp\/v2\/posts\/982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bds-bayern.de\/olching\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bds-bayern.de\/olching\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bds-bayern.de\/olching\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bds-bayern.de\/olching\/wp-json\/wp\/v2\/comments?post=982"}],"version-history":[{"count":0,"href":"https:\/\/www.bds-bayern.de\/olching\/wp-json\/wp\/v2\/posts\/982\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bds-bayern.de\/olching\/wp-json\/wp\/v2\/media\/983"}],"wp:attachment":[{"href":"https:\/\/www.bds-bayern.de\/olching\/wp-json\/wp\/v2\/media?parent=982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bds-bayern.de\/olching\/wp-json\/wp\/v2\/categories?post=982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bds-bayern.de\/olching\/wp-json\/wp\/v2\/tags?post=982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}